{"id":7487,"date":"2022-06-09T10:17:00","date_gmt":"2022-06-09T08:17:00","guid":{"rendered":"http:\/\/www.teatrostudio.it\/?p=7487"},"modified":"2023-01-03T11:44:03","modified_gmt":"2023-01-03T10:44:03","slug":"museion-2022-in-nome-della-madre","status":"publish","type":"post","link":"https:\/\/www.teatrostudio.it\/index.php\/museion-2022-in-nome-della-madre\/","title":{"rendered":"Museion 2022 &#8211; IN NOME DELLA MADRE"},"content":{"rendered":"<p style=\"text-align: center;\">ultimo appuntamento della Rassegna del Progetto Museion<br \/>\n(Sistema Museale del Lago di Bolsena, 9 aprile-24 giugno 2022)<\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #ffcc00;\">\u201cIN NOME DELLA MADRE\u201d<\/span><\/h2>\n<p style=\"text-align: center;\">Tratto dall\u2019omonimo racconto di Erri de Luca,<\/p>\n<p style=\"text-align: center;\">con inserti musicali da La buona Novella di Fabrizio De Andr\u00e9<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #ffcc00;\">25 GIUGNO 2022 ORE 18.00<\/span><\/strong><br \/>\n<strong> MUSEO DEL COSTUME FARNESIANO DI GRADOLI (VT)<\/strong><br \/>\n<a href=\"\/public\/Locandine-Museion-2022-Gradoli.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-7464\" title=\"Locandine Museion 2022 Gradoli\" src=\"\/public\/Locandine-Museion-2022-Gradoli-212x300.png\" alt=\"in nome della madre - erri de luca\" width=\"212\" height=\"300\" srcset=\"\/public\/Locandine-Museion-2022-Gradoli-212x300.png 212w, \/public\/Locandine-Museion-2022-Gradoli-723x1024.png 723w, \/public\/Locandine-Museion-2022-Gradoli.png 1414w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/a><br \/>\n\u201cLe notizie su Miri\u00e0m provengono dalle pagine di Matteo e di Luca.<br \/>\nMa non \u00e8 scritto nei loro libri che nella stalla non c\u2019erano levatrici.<br \/>\nMiriam partor\u00ec da sola e questo \u00e8 il maggior prodigio della nativit\u00e0:<br \/>\nla perizia di una giovane madre\u201d.<\/p>\n<p style=\"text-align: center;\">\u201cIn nome del padre\u201d, inaugura il segno della croce. \u201cIn nome della madre, s\u2019inaugura la vita\u201d.<\/p>\n<p style=\"text-align: center;\"><strong>Interpreti<\/strong><br \/>\nEnrica Pistolesi, Daniela Marretti, Luca Pierini<\/p>\n<p style=\"text-align: center;\"><strong>Clarinetto e voce<\/strong><br \/>\nFrancesco Melani<\/p>\n<p style=\"text-align: center;\"><strong>Chitarra<\/strong><br \/>\nPaolo Mari<\/p>\n<p style=\"text-align: center;\"><strong>Regia<\/strong><br \/>\n<em><strong>Daniela Marretti<\/strong><\/em><\/p>\n<p style=\"text-align: center;\">La partecipazione alle iniziative \u00e8 gratuita<\/p>\n<p style=\"text-align: center;\"><a href=\"\/public\/Madre_museion2022-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-7523\" title=\"Madre_museion2022 (2)\" src=\"\/public\/Madre_museion2022-2-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"\/public\/Madre_museion2022-2-300x200.jpg 300w, \/public\/Madre_museion2022-2-1024x683.jpg 1024w, \/public\/Madre_museion2022-2.jpg 1079w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><span style=\"font-family: Verdana; font-size: x-small;\">foto di Simona Soprano &#8211; archivio Simulabo<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffcc99;\"><strong>PRENOTAZIONE OBBLIGATORIA<\/strong><\/span><\/p>\n<p style=\"text-align: center;\">Per informazioni e prenotazioni: L\u2019Ape Regina Soc. Coop. ARL<br \/>\nTelefono (anche WhatsApp): 388 8568841<br \/>\nMail: eventi@laperegina.it<\/p>\n<p style=\"text-align: center;\">*****<\/p>\n<h2 style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><span style=\"color: #ffcc00;\"><a title=\"Museion 2022 - rassegna completa\" href=\"http:\/\/www.teatrostudio.it\/index.php\/museion-2022-rassegna-completa\/\"><span style=\"color: #ffcc00; text-decoration: underline;\">MUSEION 2022 &#8211; RASSEGNA COMPLETA<\/span><\/a><\/span><\/span><\/h2>\n<h4 style=\"text-align: center;\"><a href=\"\/public\/Manifesto-Completo-Museion-2022-leggero.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"Manifesto Museion 2022\" src=\"\/public\/Manifesto-Completo-Museion-2022-leggero-210x300.jpg\" alt=\"\" width=\"210\" height=\"300\" \/><\/a><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>ultimo appuntamento della Rassegna del Progetto Museion (Sistema Museale del Lago di Bolsena, 9 aprile-24 giugno 2022) \u201cIN<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[5,21],"tags":[],"class_list":["post-7487","post","type-post","status-publish","format-standard","hentry","category-spettacoli","category-teatro-archeologia-musei"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.teatrostudio.it\/index.php\/wp-json\/wp\/v2\/posts\/7487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.teatrostudio.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.teatrostudio.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.teatrostudio.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.teatrostudio.it\/index.php\/wp-json\/wp\/v2\/comments?post=7487"}],"version-history":[{"count":10,"href":"https:\/\/www.teatrostudio.it\/index.php\/wp-json\/wp\/v2\/posts\/7487\/revisions"}],"predecessor-version":[{"id":7494,"href":"https:\/\/www.teatrostudio.it\/index.php\/wp-json\/wp\/v2\/posts\/7487\/revisions\/7494"}],"wp:attachment":[{"href":"https:\/\/www.teatrostudio.it\/index.php\/wp-json\/wp\/v2\/media?parent=7487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.teatrostudio.it\/index.php\/wp-json\/wp\/v2\/categories?post=7487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.teatrostudio.it\/index.php\/wp-json\/wp\/v2\/tags?post=7487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}